{"id":4857,"date":"2021-11-24T14:25:19","date_gmt":"2021-11-24T05:25:19","guid":{"rendered":"https:\/\/www.e-expo.net\/event\/?p=4857"},"modified":"2021-10-12T10:24:05","modified_gmt":"2021-10-12T01:24:05","slug":"211124_01","status":"publish","type":"post","link":"https:\/\/www.e-expo.net\/event\/foods\/2021\/11\/211124_01.html","title":{"rendered":"\u30a2\u30b0\u30ed\u30fb\u30a4\u30ce\u30d9\u30fc\u30b7\u30e7\u30f32021"},"content":{"rendered":"<div class=\"add_expo_area\">\n<div class=\"add_expo_box\">\n<div class=\"add_expo_item\">\u4f1a\u671f<\/div>\n<div class=\"add_expo_detail\">2021\/11\/24\uff08\u6c34\uff09\uff5e26\uff08\u91d1\uff09<\/div>\n<div class=\"clear\"><\/div>\n<\/div>\n<div class=\"add_expo_box\">\n<div class=\"add_expo_item\">\u958b\u50ac\u5834\u6240<\/div>\n<div class=\"add_expo_detail\">\u6771\u4eac\u30d3\u30c3\u30b0\u30b5\u30a4\u30c8\u3000\u9752\u6d77\u5c55\u793a\u68df<\/div>\n<div class=\"clear\"><\/div>\n<\/div>\n<div class=\"add_expo_box\">\n<div class=\"add_expo_item\">\u6982\u8981<\/div>\n<div class=\"add_expo_detail\">\u65e5\u672c\u306e\u8fb2\u696d\u30d3\u30b8\u30cd\u30b9\u306e\u30d0\u30ea\u30e5\u30fc\u30c1\u30a7\u30fc\u30f3\u5168\u4f53\u306b\u95a2\u9023\u3059\u308b\u6700\u5148\u7aef\u6280\u8853\u3068\u88fd\u54c1\u3092\u5c55\u793a\u3059\u308b\u5c02\u9580\u5c55\u793a\u4f1a<\/div>\n<div class=\"clear\"><\/div>\n<\/div>\n<div class=\"add_expo_box\">\n<div class=\"add_expo_item\">\u4e3b\u50ac<\/div>\n<div class=\"add_expo_detail\">\u4e00\u822c\u793e\u56e3\u6cd5\u4eba\u65e5\u672c\u80fd\u7387\u5354\u4f1a<\/div>\n<div class=\"clear\"><\/div>\n<\/div>\n<div class=\"add_expo_box\">\n<div class=\"add_expo_item\">\u5165\u5834<\/div>\n<div class=\"add_expo_detail\">\u7121\u6599\uff08\u305f\u3060\u3057\u3001\u6848\u5185\u72b6\u3082\u3057\u304f\u306f\u6765\u5834WEB\u4e8b\u524d\u767b\u9332\u8a3c\u6301\u53c2\u304c\u5fc5\u8981\uff09<\/div>\n<div class=\"clear\"><\/div>\n<\/div>\n<div class=\"add_expo_box\">\n<div class=\"add_expo_item\">\u540c\u6642\u958b\u50ac\u5c55<\/div>\n<div class=\"add_expo_detail\">\u30a2\u30b0\u30ea\u30d3\u30b8\u30cd\u30b9\u5275\u51fa\u30d5\u30a7\u30a2<br \/>\n\u30e1\u30f3\u30c6\u30ca\u30f3\u30b9\u30fb\u30ec\u30b8\u30ea\u30a8\u30f3\u30b9TOKYO2021<br \/>\n\u7b2c14\u56de \u751f\u7523\u30b7\u30b9\u30c6\u30e0\u898b\u3048\u308b\u5316\u5c55<br \/>\n\u7b2c7\u56de \u56fd\u969b\u30c9\u30ed\u30fc\u30f3\u5c55<\/div>\n<div class=\"clear\"><\/div>\n<\/div>\n<div class=\"add_expo_box\">\n<div class=\"add_expo_item\">\u516c\u5f0f\u30b5\u30a4\u30c8<\/div>\n<div class=\"add_expo_detail\"><a href=\"https:\/\/jma-agro.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/jma-agro.com\/<\/a><\/div>\n<div class=\"clear\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u4f1a\u671f 2021\/11\/24\uff08\u6c34\uff09\uff5e26\uff08\u91d1\uff09 \u958b\u50ac\u5834\u6240 \u6771\u4eac\u30d3\u30c3\u30b0\u30b5\u30a4\u30c8\u3000\u9752\u6d77\u5c55\u793a\u68df \u6982\u8981 \u65e5\u672c\u306e\u8fb2\u696d\u30d3\u30b8\u30cd\u30b9\u306e\u30d0\u30ea\u30e5\u30fc\u30c1\u30a7\u30fc\u30f3\u5168\u4f53\u306b\u95a2\u9023\u3059\u308b\u6700\u5148\u7aef\u6280\u8853\u3068\u88fd\u54c1\u3092\u5c55\u793a\u3059\u308b\u5c02\u9580\u5c55\u793a\u4f1a \u4e3b\u50ac \u4e00\u822c\u793e\u56e3\u6cd5\u4eba\u65e5 &#8230; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.e-expo.net\/event\/wp-json\/wp\/v2\/posts\/4857"}],"collection":[{"href":"https:\/\/www.e-expo.net\/event\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.e-expo.net\/event\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.e-expo.net\/event\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.e-expo.net\/event\/wp-json\/wp\/v2\/comments?post=4857"}],"version-history":[{"count":2,"href":"https:\/\/www.e-expo.net\/event\/wp-json\/wp\/v2\/posts\/4857\/revisions"}],"predecessor-version":[{"id":4859,"href":"https:\/\/www.e-expo.net\/event\/wp-json\/wp\/v2\/posts\/4857\/revisions\/4859"}],"wp:attachment":[{"href":"https:\/\/www.e-expo.net\/event\/wp-json\/wp\/v2\/media?parent=4857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.e-expo.net\/event\/wp-json\/wp\/v2\/categories?post=4857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.e-expo.net\/event\/wp-json\/wp\/v2\/tags?post=4857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}